{"id":1042,"date":"2015-03-16T11:09:05","date_gmt":"2015-03-16T11:09:05","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=1042"},"modified":"2015-03-16T11:41:18","modified_gmt":"2015-03-16T11:41:18","slug":"las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/","title":{"rendered":"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino"},"content":{"rendered":"<p>Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (<strong>un 94% del total<\/strong>) fueron ocupados por trabajadoras en esta franja de edad. El &#8216;efecto rebote&#8217; tras la destrucci\u00f3n de empleo y la necesidad de aumentar los ingresos en los hogares ha hecho que sean las mujeres de m\u00e1s edad las que planten cara con m\u00e1s \u00e9xito al desempleo.<\/p>\n<p>El &#8216;II informe de la mujer en riesgo de exclusi\u00f3n en el mercado laboral&#8217; que ha elaborado la Fundaci\u00f3n Adecco pone de manifiesto esta tendencia. Aunque las mujeres mayores de 45 han sido durante la crisis<strong>uno de los grupos m\u00e1s castigados<\/strong> de las estad\u00edsticas de desempleo, tambi\u00e9n lideran la recuperaci\u00f3n.<\/p>\n<p>Adecco se basa en los datos de la \u00faltima Encuesta de Poblaci\u00f3n Activa (EPA) que apuntaron ya a esta <strong>predilecci\u00f3n por el &#8216;empleo senior&#8217; <\/strong>en las contrataciones: de los 433.900 empleos netos que se crearon el a\u00f1o pasado, el 81% de los mismos fueron para hombres y mujeres mayores de 45 a\u00f1os. Las mujeres j\u00f3venes son la otra cara de la moneda: En 2014, se destruyeron 44.600 empleos de j\u00f3venes entre 20 y 34 a\u00f1os.<\/p>\n<p>Aunque las cifras son esperanzadoras, habr\u00e1 que esperar a que la tendencia se consolide, ya que esta franja de edad <strong>sigue sufriendo tambi\u00e9n el desempleo<\/strong> y sobre todo, el paro de larga duraci\u00f3n. A continuaci\u00f3n, desgranamos las claves de este repunte en el empleo femenino de m\u00e1s edad:<\/p>\n<ol>\n<li><strong>El efecto rebote<\/strong>. El grupo de mayores de 45 fue uno de los sectores m\u00e1s afectados por la crisis. Al tener un n\u00famero elevado de desempleadas, tambi\u00e9n son las que acaparan m\u00e1s puestos de trabajo nuevos. La velocidad a la que est\u00e1n ocupando estas vacantes sugiere un \u00abefecto rebote\u00bb, seg\u00fan apunta Adecco.<\/li>\n<li><strong>Capear la crisis.<\/strong> La debacle econ\u00f3mica ha llevado al aumento del paro y la precariedad. Por ello, muchos hogares han vistos mermados sus ingresos y muchas mujeres de esta edad, que permanec\u00edan inactivas, se han visto obligadas a buscar trabajo. En 2014, un total de 54.200 mujeres entre 45 y 65 a\u00f1os abandonaron las actividades del hogar para buscar un empleo. En el otro lado, unos 15.500 menores de 30 a\u00f1os se retiraron del mercado para seguir estudiando o buscar otras alternativas.<\/li>\n<li><strong>Una poblaci\u00f3n m\u00e1s envejecida.<\/strong> Tambi\u00e9n hay una cuesti\u00f3n puramente estad\u00edstica tras estas cifras. En este momento, en Espa\u00f1a hay 112 mayores de 64 a\u00f1os por cada 100 menores de 16. Esto significa que los mayores de 45 a\u00f1os (nacidos en el &#8216;baby boom&#8217;) representan el 40% de la poblaci\u00f3n activa. Las empresas comienzan a adaptarse a esta nueva realidad en una sociedad donde la esperanza de vida ha aumentado en las \u00faltimas d\u00e9cadas.<\/li>\n<li><strong>La experiencia y los resultados a corto plazo<\/strong>. El hecho de que los &#8216;senior&#8217; tengan m\u00e1s experiencia, hace que den resultados m\u00e1s pronto que los j\u00f3venes, que tienen que adquirir todos los conocimientos que los mayores de 45 ya dominan. La devaluaci\u00f3n salarial tambi\u00e9n ha influ\u00eddo en que la especializaci\u00f3n resulte m\u00e1s barata que antes de la crisis.<\/li>\n<li><strong>Sectores m\u00e1s din\u00e1micos.<\/strong> Desde 2007, se han generado 660.800 empleos para mujeres mayores de 45 a\u00f1os, mientras que se han destruido 55.200 puestos detrabajo masculinos. La explicaci\u00f3n podr\u00eda estar en los sectores donde se concentra cada sexo. Mientras que la construcci\u00f3n o la automoci\u00f3n (copados por los hombres)han sido m\u00e1s castigados por la crisis, las mujeres han elegido sectores m\u00e1s din\u00e1micos como el de servicios, que han sufrido menos la destrucci\u00f3n de empleo.<\/li>\n<li><strong>Las mujeres con discapacidad, otra apuesta segura<\/strong>: Seg\u00fan la Fundaci\u00f3n Adecco, la contrataci\u00f3n de mujeres con discapacidad se increment\u00f3 un 30% el a\u00f1o pasado. El perfil medio de esta nueva trabajadora es el de una joven entre 25 y 35 a\u00f1os, con estudios elementales,discapacidad f\u00edsica y un contrato en el sector servicios como dependienta (6%) u operaria (4%).<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (un 94% del total) fueron ocupados por trabajadoras en esta franja de edad. El &#8216;efecto rebote&#8217; tras la destrucci\u00f3n[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1042","post","type-post","status-publish","format-standard","hentry","category-emprendedores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino - Mujer Rural Emprendedora<\/title>\n<meta name=\"description\" content=\"Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (un 94% del total) fueron ocupados por trabajadoras en esta franja de edad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (un 94% del total) fueron ocupados por trabajadoras en esta franja de edad.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-16T11:09:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-16T11:41:18+00:00\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino\",\"datePublished\":\"2015-03-16T11:09:05+00:00\",\"dateModified\":\"2015-03-16T11:41:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/\"},\"wordCount\":698,\"commentCount\":0,\"articleSection\":[\"Emprendedores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/\",\"name\":\"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"datePublished\":\"2015-03-16T11:09:05+00:00\",\"dateModified\":\"2015-03-16T11:41:18+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"description\":\"Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (un 94% del total) fueron ocupados por trabajadoras en esta franja de edad.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino - Mujer Rural Emprendedora","description":"Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (un 94% del total) fueron ocupados por trabajadoras en esta franja de edad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/","og_locale":"es_ES","og_type":"article","og_title":"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino - Mujer Rural Emprendedora","og_description":"Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (un 94% del total) fueron ocupados por trabajadoras en esta franja de edad.","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-03-16T11:09:05+00:00","article_modified_time":"2015-03-16T11:41:18+00:00","author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino","datePublished":"2015-03-16T11:09:05+00:00","dateModified":"2015-03-16T11:41:18+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/"},"wordCount":698,"commentCount":0,"articleSection":["Emprendedores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/","name":"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"datePublished":"2015-03-16T11:09:05+00:00","dateModified":"2015-03-16T11:41:18+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"description":"Las mujeres de m\u00e1s de 45 a\u00f1os se sit\u00faan a la cabeza de la creaci\u00f3n de empleo femenino en Espa\u00f1a. De los 182.400 trabajos netos que se crearon en 2014, 171.500 (un 94% del total) fueron ocupados por trabajadoras en esta franja de edad.","breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/las-mujeres-mayores-de-45-anos-a-la-cabeza-del-nuevo-empleo-femenino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las mujeres mayores de 45 a\u00f1os, a la cabeza del nuevo empleo femenino"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":1,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1042\/revisions"}],"predecessor-version":[{"id":1043,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1042\/revisions\/1043"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=1042"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}