{"id":1188,"date":"2015-04-13T15:00:57","date_gmt":"2015-04-13T15:00:57","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=1188"},"modified":"2015-04-13T15:00:57","modified_gmt":"2015-04-13T15:00:57","slug":"el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/","title":{"rendered":"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os"},"content":{"rendered":"<p>El Gobierno de Cantabria ha dado el visto bueno al <span id=\"U30103458623133pEH\">contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia<\/span>, que supondr\u00e1 un coste de 28,5 millones de euros durante un periodo de tres a\u00f1os.<\/p>\n<p>En su reuni\u00f3n semanal, celebrada ayer, tambi\u00e9n el Ejecutivo que preside Ignacio Diego ha licitado, por importe de 2.945.148 euros, la construcci\u00f3n de la nueva lonja y la sede de la cofrad\u00eda de pescadores de Colindres, cuya ejecuci\u00f3n tiene un plazo de dos a\u00f1os.<\/p>\n<p>El servicio de ayuda a domicilio, seg\u00fan recuerda el Ejecutivo en nota de prensa, facilita un conjunto de atenciones en su domicilio a las personas dependientes, para cubrir sus necesidades de vida diaria.<\/p>\n<p>As\u00ed se promueve su permanencia y autonom\u00eda en el medio habitual familiar de la persona dependiente, y se preserva su capacidad funcional lo que impide, dentro de lo posible, su deterioro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Cantabria ha dado el visto bueno al contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia, que supondr\u00e1 un coste de 28,5 millones de euros durante un periodo de tres a\u00f1os. En su reuni\u00f3n semanal, celebrada ayer, tambi\u00e9n el Ejecutivo que preside[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1188","post","type-post","status-publish","format-standard","hentry","category-ayuda-a-domicilio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os - Mujer Rural Emprendedora<\/title>\n<meta name=\"description\" content=\"El Gobierno de Cantabria ha dado el visto bueno al contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Cantabria ha dado el visto bueno al contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia,\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-13T15:00:57+00:00\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os\",\"datePublished\":\"2015-04-13T15:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/\"},\"wordCount\":171,\"commentCount\":0,\"articleSection\":[\"Ayuda a Domicilio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/\",\"name\":\"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"datePublished\":\"2015-04-13T15:00:57+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"description\":\"El Gobierno de Cantabria ha dado el visto bueno al contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia,\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os - Mujer Rural Emprendedora","description":"El Gobierno de Cantabria ha dado el visto bueno al contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os - Mujer Rural Emprendedora","og_description":"El Gobierno de Cantabria ha dado el visto bueno al contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia,","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-04-13T15:00:57+00:00","author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os","datePublished":"2015-04-13T15:00:57+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/"},"wordCount":171,"commentCount":0,"articleSection":["Ayuda a Domicilio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/","name":"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"datePublished":"2015-04-13T15:00:57+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"description":"El Gobierno de Cantabria ha dado el visto bueno al contrato para el servicio de ayuda a domicilio para personas en situaci\u00f3n de dependencia,","breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-gobierno-de-cantabria-aprueba-el-contrato-de-ayuda-a-domicilio-por-285-millones-en-3-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Cantabria aprueba el contrato de ayuda a domicilio por 28,5 millones en 3 a\u00f1os"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=1188"}],"version-history":[{"count":1,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1188\/revisions"}],"predecessor-version":[{"id":1189,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1188\/revisions\/1189"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=1188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=1188"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=1188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}