{"id":1194,"date":"2015-04-13T15:24:09","date_gmt":"2015-04-13T15:24:09","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=1194"},"modified":"2015-04-13T15:24:09","modified_gmt":"2015-04-13T15:24:09","slug":"la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/","title":{"rendered":"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares"},"content":{"rendered":"<p>La Consejer\u00eda de Familia e Igualdad de Oportunidades publica este lunes en el Bolet\u00edn Oficial de Castilla y Le\u00f3n (Bocyl) una orden que permitir\u00e1 a 37.000 personas compatibilizar simult\u00e1neamente la ayuda que reciben por cuidados familiares con otras ayudas para adquirir un servicio profesional como ayuda a domicilio, promoci\u00f3n e la autonom\u00eda personal o centro de d\u00eda.<\/p>\n<p>Esto supone incrementar en un cinco por ciento las cuant\u00edas mensuales que recib\u00edan antes de la crisis para que puedan adquirir un servicio profesional. De esta forma, un dependiente de la Comunidad percibir\u00e1 al mes un 24 por ciento m\u00e1s que en otras comunidades, seg\u00fan han destacado fuentes de la Consejer\u00eda.<\/p>\n<p>La orden establece que las personas dependientes mayores de edad, con grados I, II y III que son beneficiarias de la ayuda econ\u00f3mica por cuidados en el entorno familiar tendr\u00e1n derecho a compatibilizar, de forma simult\u00e1nea, esa ayuda con otras prestaciones para obtener servicios profesionales.<\/p>\n<p>En concreto, las personas de grado III que cuentan con cuidados en el entorno familiar percibir\u00e1n hasta 479 euros al mes, frente a los 388 euros de otras autonom\u00edas, para que cuenten tambi\u00e9n con servicios profesionales. Por su parte, los de grado II pasar\u00e1n a percibir un m\u00e1ximo al mes de 332 euros -63 euros m\u00e1s que en otras comunidades-. Y los de grado I recibir\u00e1n 189 euros mensuales -36 m\u00e1s que en el resto de Espa\u00f1a-.<\/p>\n<p>La intensidad mensual de estas prestaciones simult\u00e1neas aparece recogida en la orden. En el caso del servicio de ayuda a domicilio, la intensidad depender\u00e1 de su grado de Dependencia. En concreto, ser\u00e1 de once horas para las personas de grado III, de ocho horas para las del grado II y de cuatro horas para las de grado I. En el caso del servicio de promoci\u00f3n de la autonom\u00eda personal y del servicio de centro de d\u00eda, las intensidades ser\u00e1n equivalentes a la necesaria para alcanzar el nivel de apoyo total de la prestaci\u00f3n econ\u00f3mica en el entorno familiar que exist\u00eda antes de la crisis.<\/p>\n<p>Se trata, por tanto, de complementar con servicios profesionales la atenci\u00f3n de las personas en situaci\u00f3n de Dependencia que son cuidadas en su entorno familiar.<\/p>\n<p>La Consejer\u00eda estima que este avance supondr\u00e1 la creaci\u00f3n de 8.000 nuevos puestos de trabajo asociados a la Dependencia, que se sumar\u00edan a los 16.600 profesionales vinculados actualmente a la Dependencia -.500 profesionales generados en la presente legislatura-, lo que \u00abconsagra a Castilla y Le\u00f3n como la Comunidad que m\u00e1s empleo genera en este sector\u00bb.<\/p>\n<p>Fuente:<a title=\"Ayudas para familiares que presten servicio a domicilio\" href=\"http:\/\/www.20minutos.es\/noticia\/2430414\/0\/junta-complementara-con-servicios-profesionales-ayudas-dependientes-que-son-atendidos-por-sus-familiares\/\" target=\"_blank\"> 20 minutos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer\u00eda de Familia e Igualdad de Oportunidades publica este lunes en el Bolet\u00edn Oficial de Castilla y Le\u00f3n (Bocyl) una orden que permitir\u00e1 a 37.000 personas compatibilizar simult\u00e1neamente la ayuda que reciben por cuidados familiares con otras ayudas para adquirir un servicio profesional como ayuda a domicilio, promoci\u00f3n e[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1194","post","type-post","status-publish","format-standard","hentry","category-ayuda-a-domicilio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares - Mujer Rural Emprendedora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"La Consejer\u00eda de Familia e Igualdad de Oportunidades publica este lunes en el Bolet\u00edn Oficial de Castilla y Le\u00f3n (Bocyl) una orden que permitir\u00e1 a 37.000 personas compatibilizar simult\u00e1neamente la ayuda que reciben por cuidados familiares con otras ayudas para adquirir un servicio profesional como ayuda a domicilio, promoci\u00f3n e[...]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-13T15:24:09+00:00\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares\",\"datePublished\":\"2015-04-13T15:24:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/\"},\"wordCount\":468,\"commentCount\":0,\"articleSection\":[\"Ayuda a Domicilio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/\",\"name\":\"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"datePublished\":\"2015-04-13T15:24:09+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares - Mujer Rural Emprendedora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/","og_locale":"es_ES","og_type":"article","og_title":"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares - Mujer Rural Emprendedora","og_description":"La Consejer\u00eda de Familia e Igualdad de Oportunidades publica este lunes en el Bolet\u00edn Oficial de Castilla y Le\u00f3n (Bocyl) una orden que permitir\u00e1 a 37.000 personas compatibilizar simult\u00e1neamente la ayuda que reciben por cuidados familiares con otras ayudas para adquirir un servicio profesional como ayuda a domicilio, promoci\u00f3n e[...]","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-04-13T15:24:09+00:00","author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares","datePublished":"2015-04-13T15:24:09+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/"},"wordCount":468,"commentCount":0,"articleSection":["Ayuda a Domicilio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/","name":"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"datePublished":"2015-04-13T15:24:09+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/la-junta-de-castilla-y-leon-complementara-con-servicios-profesionales-las-ayudas-a-dependientes-que-son-atendidos-por-sus-familiares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Junta de Castilla y Le\u00f3n complementar\u00e1 con servicios profesionales las ayudas a dependientes que son atendidos por sus familiares"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=1194"}],"version-history":[{"count":1,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1194\/revisions"}],"predecessor-version":[{"id":1195,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1194\/revisions\/1195"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=1194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=1194"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=1194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}