{"id":1198,"date":"2015-04-13T16:53:54","date_gmt":"2015-04-13T16:53:54","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=1198"},"modified":"2015-04-13T16:53:54","modified_gmt":"2015-04-13T16:53:54","slug":"el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/","title":{"rendered":"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM"},"content":{"rendered":"<p>La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan L\u00f3pez- Casero, \u201cInternet es un gran mercado que tenemos que explorar y conquistar, pero debemos hacerlo con inteligencia, sensatez y sobre todo con conocimiento y estrategia. Ambas cosas, conocimiento y estrategia son las que aporta este programa a nuestros empresarios y emprendedores\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan L\u00f3pez Casero \u00abla mayor\u00eda de nosotros nos hemos convertido r\u00e1pidamente en consumidores de la econom\u00eda digital, sin embargo, a\u00fan estamos lejos de integrar los canales y las herramientas digitales (web, redes sociales, e mail marketing Mobile marketing, etc.) en nuestro negocio para ganar de forma real m\u00e1s rentabilidad\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>El programa que est\u00e1 dirigido a empresarios, directivos y emprendedores, pretende ampliar la formaci\u00f3n y conocimientos en las disciplinas digitales para dirigir y gestionar las empresas con \u00e9xito en el \u00e1mbito de la econom\u00eda digital.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cLa Econom\u00eda digital te permite un cambio de enfoque en tu modelo de negocio, ya que te obliga a pensar como tu cliente y te permite trabajar e innovar con tu cliente, algo absolutamente disruptivo para muchos negocios, pero muy importante de cara a que tu negocio siga existiendo y siendo rentable hoy\u00bb afirm\u00f3 L\u00f3pez Casero.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Programa de Negocio Digital e-DIR<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La Fundaci\u00f3n Caja Rural Castilla-La Mancha, ha dise\u00f1ado este programa para que los participantes reciban, adem\u00e1s de la formaci\u00f3n, un servicio de consultor\u00eda individual en materia de competencias digitales, en el que obtendr\u00e1n un diagn\u00f3stico de su empresa, detectar\u00e1n d\u00f3nde mejorarla y elaborar\u00e1n su Plan Individual de Negocio Digital.<\/p>\n<p>&nbsp;<\/p>\n<p>En los diferentes m\u00f3dulos planteados para este curso, el Programa e-Dir contar\u00e1 con profesores y consultores del Instituto de Econom\u00eda Digital en activo. Algunos de ellos desarrollan su actividad en las principales consultoras y agencias especializadas\u00a0 y otros proceden de importantes sectores empresariales de nuestro pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p>El claustro estar\u00e1 compuesto por destacados profesionales del Marketing Relacional; Marketing Directo y Digital; Redes Sociales; CRM; eCommerce; Proximity y Mobile Marketing.<\/p>\n<p>&nbsp;<\/p>\n<p>El programa comenzar\u00e1 a impartirse\u00a0el 30 de abril\u00a0en Toledo y consta de 13 jornadas formativas presenciales, sesiones de consultor\u00eda personalizada presencial y on-line para cada empresa, Masterclass y encuentros de networking con profesionales del sector.<\/p>\n<p>&nbsp;<\/p>\n<p>Las inscripciones podr\u00e1n realizarse a trav\u00e9s de <a href=\"http:\/\/www.fundacioncajaruralcastillalamancha.es\/\">www.fundacioncajaruralcastillalamancha.es<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME &nbsp; Seg\u00fan L\u00f3pez- Casero, \u201cInternet es un gran mercado que tenemos que explorar y conquistar, pero debemos[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1198","post","type-post","status-publish","format-standard","hentry","category-emprendedores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM - Mujer Rural Emprendedora<\/title>\n<meta name=\"description\" content=\"La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-13T16:53:54+00:00\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM\",\"datePublished\":\"2015-04-13T16:53:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/\"},\"wordCount\":450,\"commentCount\":0,\"articleSection\":[\"Emprendedores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/\",\"name\":\"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"datePublished\":\"2015-04-13T16:53:54+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"description\":\"La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM - Mujer Rural Emprendedora","description":"La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/","og_locale":"es_ES","og_type":"article","og_title":"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM - Mujer Rural Emprendedora","og_description":"La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-04-13T16:53:54+00:00","author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM","datePublished":"2015-04-13T16:53:54+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/"},"wordCount":450,"commentCount":0,"articleSection":["Emprendedores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/","name":"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"datePublished":"2015-04-13T16:53:54+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"description":"La directora de la Fundaci\u00f3n Caja Rural Castilla-La Mancha, Ana L\u00f3pez-Casero Beltr\u00e1n, ha presentado el Programa de Negocio Digital e-DIR, iniciativa promovida por el Instituto de Innovaci\u00f3n y Competitividad, en colaboraci\u00f3n con CEOE-CEPYME","breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/el-programa-negocio-digital-e-dir-para-pymes-llega-a-castilla-la-mancha-de-la-mano-de-la-fundacion-caja-rural-clm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"El programa \u2018Negocio Digital e-DIR\u2019 para pymes llega a Castilla la Mancha de la mano de la Fundaci\u00f3n Caja Rural CLM"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=1198"}],"version-history":[{"count":1,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1198\/revisions"}],"predecessor-version":[{"id":1199,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1198\/revisions\/1199"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=1198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=1198"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=1198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}