{"id":1289,"date":"2015-04-21T08:32:59","date_gmt":"2015-04-21T08:32:59","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=1289"},"modified":"2015-04-21T08:54:59","modified_gmt":"2015-04-21T08:54:59","slug":"tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/","title":{"rendered":"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia"},"content":{"rendered":"<div>\n<div>\n<blockquote>\n<div>\n<div>\n<div>Regresa el proyecto\u00a0<b>\u201cQUIERO SER EMPRESARIA DE \u00c9XITO\u201d<\/b>,\u00a0<b>tercera edici\u00f3n!<\/b><\/div>\n<div><\/div>\n<div>Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off line.<\/div>\n<div><\/div>\n<div>La actividad comercial tradicional se est\u00e1 deteriorando en parte por la competencia de los grandes centros comerciales. Conscientes de los grandes inconvenientes del comercio tradicional para competir estos gigantes, OMEP presenta un ciclo de talleres en los que los peque\u00f1os comercios adquieran habilidades comunicativas y herramientas con las que poder enfrentarse a sus competidores fortaleciendo sus potencialidades.<\/div>\n<div><\/div>\n<div>Aprender a dise\u00f1ar y planificar una estrategia de ventas, hacer una buena presentaci\u00f3n del producto, saber comunicar para atraer al cliente, utilizar t\u00e9cnicas emocionales para culminar la venta o usar redes sociales para vender, son algunas de las tem\u00e1ticas del ciclo.<\/div>\n<div><\/div>\n<div><b>Horario de todos los talleres:<\/b>\u00a0de 17:00 a 21:00 h<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<div>\n<div>\n<blockquote>\n<div>\n<div>\n<div><b>Lugar de impartici\u00f3n:<\/b>\u00a0CIM-M (carretera de Churra, 96)<\/div>\n<div><\/div>\n<div><strong>Inscripci\u00f3n gratuita<\/strong>.\u00a0Rellena el documento adjunto y rem\u00edtelo a\u00a0<a href=\"mailto:comunicacion@omep.es\" target=\"_blank\">comunicacion@omep.es<\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div><b>BATERIA DE TALLERES \u201cQUIERO SER EMPRESARIA DE \u00c9XITO III\u201d<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>v\u00a0\u00a0<b>TALLER \u201cHERRAMIENTAS DE VENTA ON LINE\u201d- 29 de abril de 2015<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Objetivos.<\/b><\/div>\n<div>Las herramientas de marketing y comunicaci\u00f3n que proporcionan las nuevas tecnolog\u00edas permiten a los freelances y emprendedores la puesta en marcha de acciones de publicidad, marketing y ventas que, hasta hace pocos a\u00f1os, hab\u00edan estado reservadas a las grandes empresas. Sin embargo, estos recursos deben ser empleados de manera estrat\u00e9gica y englobados en una estrategia m\u00e1s amplia, para la cual deben tenerse en cuenta otros factores, como conocer algunas pautas b\u00e1sicas del comportamiento del consumidor y de orientaci\u00f3n al cliente, para que la transmisi\u00f3n del mensaje pueda generar las ventas necesarias.<\/div>\n<div><\/div>\n<div>En el taller, se estudiar\u00e1n herramientas al alcance de freelances y emprendedores para ser eficaces en su e-mail marketing.<\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Contenido.<\/b><\/div>\n<div>\u00b7\u00a0Venta por email. Heramientas gratuitas.\u00a0<span lang=\"EN-US\">Mailchimp.<\/span><\/div>\n<div>\u00b7\u00a0<span lang=\"EN-US\">Email Marketing<\/span><\/div>\n<div>\u00b7\u00a0<span lang=\"EN-US\">Marketing en redes sociales.\u00a0<\/span>Twitter y Linkedin<\/div>\n<div><\/div>\n<div>Ponente:\u00a0<b>Mar Rodriguez<\/b>,<a href=\"http:\/\/aqueresocialmedia.com\/\">\u00a0Aquere Social Media<\/a><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>v\u00a0\u00a0<b>TALLER \u201cGESTI\u00d3N DE LA IMAGEN PROFESIONAL.HABILIDADES SOCIALES Y COMUNICACI\u00d3N NO VERBAL\u201d \u2013 14 de mayo de 2015<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>O<\/b><b>bjetivos<\/b><\/div>\n<div>Ense\u00f1ar a mejorar la imagen personal y su presentaci\u00f3n ante el cliente para llevar la venta al \u00e9xito. Hacer una presentaci\u00f3n del producto coherente y estructurada con la que se facilite la venta.<\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Contenido.<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>\u00b7\u00a0La imagen personal como estrategia de \u00e9xito.<\/div>\n<div>\u00b7\u00a0El lenguaje no verbal y su influencia en tu proyecto en tu proyecto personal y profesoinal.<\/div>\n<div>\u00b7\u00a0Dec\u00e1logo de cortes\u00eda y habilidades en las relaciones sociales y empresariales<\/div>\n<div><\/div>\n<div>Ponente:\u00a0<b>Carmen Mart\u00ednez Morales<\/b>, directora del\u00a0<a href=\"https:\/\/iiimoda.wordpress.com\/\" target=\"_blank\">Instituto Internacional de Imagen y Moda.<\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div>v\u00a0\u00a0<b>TALLER \u201cNEUROMARKETING Y STORYTELLING: EL PODER DE LAS NEURONAS ESPEJO\u201d \u2013\u00a0 28 de mayo de 2015<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Objetivos.<\/b><\/div>\n<div>&#8211; El objetivo principal es aplicar el marketing a los procesos de comunicaci\u00f3n de la empresa desde una perspectiva emocional para:<\/div>\n<div>&#8211; Captar y fidelizar al cliente desde un v\u00ednculo emocional basado en la confianza.<\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Contenidos.<\/b><\/div>\n<div>&#8211; Storytelling. La historia de la empresa<\/div>\n<div>&#8211; Marketing emocional. Los v\u00ednculos emocionales en las negociaciones.<\/div>\n<div>&#8211; Comunicaci\u00f3n. Aprender a comunicar una marca.<\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>Ponente:\u00a0<b>Patrizia Gea<\/b>,\u00a0<a href=\"http:\/\/www.laescueladelabuenasuerte.com\/\" target=\"_blank\">La escuela de la buena suerte<b>.<\/b><\/a><b><\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div>v\u00a0\u00a0<b>TALLER \u201cEL ARTE DE VENDER. LA IMPORTANCIA DE SABER PRESENTAR EFICAZMENTE\u201d \u2013 11 de Junio de 2015<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Objetivo.<\/b><\/div>\n<div>Alinear las variables necesarias para conseguir que nuestra presentaci\u00f3n de la empresa y del producto sea eficaz y culmine la venta.<\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Contenido.<\/b><\/div>\n<div>Bloque 1. Hablar en p\u00fablico. Nosotros y la audiencia.<\/div>\n<div>\u00b7\u00a0Nuestras Fortalezas y debilidades<\/div>\n<div>\u00b7\u00a0Miedo esc\u00e9nico, como manejarlo y dominarlo.<\/div>\n<div><\/div>\n<div>Bloque 2. Hablar en p\u00fablico la importancia de una buena presentaci\u00f3n.<\/div>\n<div>\u00b7\u00a0Lo primeo a tener claro, \u00bfQue queremos conseguir?<\/div>\n<div>\u00b7\u00a0Preparar, planificar y elaborar la estructura de la presentaci\u00f3n.<\/div>\n<div>\u00b7\u00a0La audiencia. Comunicaci\u00f3n y argumentaci\u00f3n eficaz con la audiencia.<\/div>\n<div>\u00b7\u00a0Manejo de situaciones dif\u00edciles.<\/div>\n<div>\u00b7\u00a0Los Cierres m\u00e1s eficaces.<\/div>\n<div>\u00b7\u00a0Las preguntas de la audiencia, como manejarlas.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Bloque 3. Hablar en p\u00fablico. Consigue ser el mejor comunicador.<\/div>\n<div>\u00b7\u00a0Los cuatro elementos b\u00e1sicos del buen comunicador:<\/div>\n<div>&#8211; personalidad del profesional,<\/div>\n<div>&#8211; Mapa facial.<\/div>\n<div>&#8211; Informaci\u00f3n verbal.<\/div>\n<div>&#8211; Informaci\u00f3n no verbal.<\/div>\n<div><\/div>\n<div>Ponentes:\u00a0<b>Maria Meseguer y Bel\u00e9n Luj\u00e1n<\/b>,\u00a0<a href=\"http:\/\/www.in-tempus.es\/\" target=\"_blank\">In tempus<\/a><\/div>\n<div><\/div>\n<div>Descarga aqu\u00ed tu folleto para la <a href=\"http:\/\/omep.es\/wp-content\/uploads\/2015\/04\/INSCRIPCI%C3%93N-QUIERO-SER-EMPRESARIA-DE-%C3%89XITO-III.doc\">INSCRIPCI\u00d3N QUIERO SER EMPRESARIA DE \u00c9XITO III<\/a><\/div>\n<div><\/div>\n<div>FUENTE: <a title=\"Tercera edicion empresaria de \u00e9xito\" href=\"http:\/\/omep.es\/\" target=\"_blank\">OMEP.ES<\/a><\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Regresa el proyecto\u00a0\u201cQUIERO SER EMPRESARIA DE \u00c9XITO\u201d,\u00a0tercera edici\u00f3n! Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1289","post","type-post","status-publish","format-standard","hentry","category-emprendedores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia - Mujer Rural Emprendedora<\/title>\n<meta name=\"description\" content=\"Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off line.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off line.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-21T08:32:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-21T08:54:59+00:00\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia\",\"datePublished\":\"2015-04-21T08:32:59+00:00\",\"dateModified\":\"2015-04-21T08:54:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/\"},\"wordCount\":736,\"commentCount\":0,\"articleSection\":[\"Emprendedores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/\",\"name\":\"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"datePublished\":\"2015-04-21T08:32:59+00:00\",\"dateModified\":\"2015-04-21T08:54:59+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"description\":\"Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off line.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia - Mujer Rural Emprendedora","description":"Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off line.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/","og_locale":"es_ES","og_type":"article","og_title":"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia - Mujer Rural Emprendedora","og_description":"Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off line.","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-04-21T08:32:59+00:00","article_modified_time":"2015-04-21T08:54:59+00:00","author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia","datePublished":"2015-04-21T08:32:59+00:00","dateModified":"2015-04-21T08:54:59+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/"},"wordCount":736,"commentCount":0,"articleSection":["Emprendedores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/","name":"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"datePublished":"2015-04-21T08:32:59+00:00","dateModified":"2015-04-21T08:54:59+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"description":"Tras los anteriores ciclos destinados al empoderamiento y gesti\u00f3n econ\u00f3mico financiera de la empresa, este a\u00f1o vamos a culminar con un ciclo de ventas y habilidades comerciales que pretende dinamizar el comercio tradicional, para que conozca las nuevas tendencias on y off line.","breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/tercera-edicion-del-programa-quiero-ser-empresaria-de-exito-en-murcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tercera edici\u00f3n del programa \u201cQuiero ser empresaria de \u00e9xito\u201d en Murcia"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=1289"}],"version-history":[{"count":1,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1289\/revisions"}],"predecessor-version":[{"id":1290,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1289\/revisions\/1290"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=1289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=1289"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=1289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}