{"id":1550,"date":"2015-06-12T10:47:37","date_gmt":"2015-06-12T10:47:37","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=1550"},"modified":"2015-06-12T10:48:34","modified_gmt":"2015-06-12T10:48:34","slug":"de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/","title":{"rendered":"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo?"},"content":{"rendered":"<p>Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos.<\/p>\n<p>Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan.<\/p>\n<p>Algunos ancianos tienen la dicha de que sus vidas sean m\u00e1s largas que las de otros, a medida que el tiempo transcurre quiz\u00e1 estos van teniendo necesidades a\u00fan m\u00e1s espec\u00edficas por ejemplo dietas mas especializadas de acuerdo a su estado de salud o atenci\u00f3n de especialistas seg\u00fan sea el caso&#8230; Todo esto a un nivel f\u00edsico estar\u00e1 cumpliendo los satisfactores primarios. Pero que acerca de los sentimientos que a ellos les embargan, de su estado de \u00e1nimo espiritual, el darse cuenta de que ya no gozan de la misma fuerza f\u00edsica que ten\u00edan cuando fueron m\u00e1s j\u00f3venes es algo que muy probablemente pueda lastimar su autoestima.<\/p>\n<p>El saber que su cuerpo a cambiado y comienza a experimentar enfermedades dif\u00edciles de sobrellevar, rutinas en las cuales saben que tienen que tomar medicamentos que probablemente nunca imaginaron los someter\u00eda a un estado a veces depresivo al saber que son dependientes de algo para continuar sus vidas.<\/p>\n<p>La soledad que experimentan al no verse rodeados en muchas ocasiones de la familia que los abandona a su suerte pensando que ya son un estorbo por su edad avanzada. Bueno la soluci\u00f3n est\u00e1 en nosotros, en darles la compa\u00f1\u00eda y la atenci\u00f3n que se merecen.<\/p>\n<p>La personas de la tercera edad van perdiendo a medida que pasa el tiempo ciertas capacidades importantes como son el sentido del o\u00eddo, la vista y el gusto entre otros&#8230; si ya no pueden saborear, ni oler, pierden entonces el inter\u00e9s por la comida, esto los puede llevar inminentemente a sufrir una desnutrici\u00f3n, indiscutiblemente est\u00e1 en nosotros el atenderlos correctamente y procurar que coman a sus horas y lo que su cuerpo necesita para mantener un balance nutricional adecuado.<\/p>\n<p>Si les ponemos el cuidado necesario ellos se alimentaran mejor y su \u00e1nimo tambi\u00e9n estar\u00e1 mucho mejor pues brindandoles compa\u00f1\u00eda podremos hacerlos sentir amados y su vida resultar\u00e1 m\u00e1s f\u00e1cil y placentera.<\/p>\n<p>Los ancianos tambi\u00e9n pierden su fuerza y agilidad es por eso que debemos preocuparnos por ayudarlos a organizar el espacio que habitan de esta forma quiz\u00e1 podremos prevenir el que tengan alg\u00fan accidente, las ca\u00eddas en la vejez son muy peligrosas, y romperse los huesos en una ca\u00edda est\u00e1 a la orden del d\u00eda, pero si nosotros les ayudamos a quitar los obst\u00e1culos para que ellos al caminar o desplazarse en la vivienda no corran peligro, estaremos cooperando para que lleguen a\u00fan con m\u00e1s probabilidades a tener una vida mucho m\u00e1s sana y fuera de peligros y riesgos. Hagan un recuento y analizen si nos aseguramos de que:<\/p>\n<p>1.-Coman bien y con esto me refiero a alimentos nutritivos y balanceados.<\/p>\n<p>2.- Tengan una supervisi\u00f3n m\u00e9dica adecuada y regular me refiero a visitas m\u00e9dicas constantes as\u00ed como ex\u00e1menes m\u00e9dicos con regularidad .<\/p>\n<p>3.- Nos aseguramos de que tomen los medicamentos recetados por su m\u00e9dico y hago hincapi\u00e9 en no permitirles auto medicaci\u00f3n ya que los ancianos son muy testarudos en algunos casos y quieren tomar lo que les receta la amiga o la comadre.<\/p>\n<p>4.- Motivarlos a hacer ejercicio ya que est\u00e9 ayudar\u00e1 a su salud al mantenerse en actividad constante.<\/p>\n<p>5.- D\u00e1ndoles atenci\u00f3n personal, dedic\u00e1ndoles tiempo, platicando con ellos, haciendolos sentir parte integral de la familia, de alguna forma pidiendoles consejos en los cuales ellos sientan que est\u00e1n aportando ideas para que esto les ayude a engrandecer su esp\u00edritu, estaremos aport\u00e1ndoles algo y demostr\u00e1ndoles que los amamos de verdad.<\/p>\n<p>Recuerden que nuestros adultos mayores necesitan sentir que son importantes como individuos, que son \u00fatiles y que son amados, compartamos con ellos cari\u00f1o, cuidados, atenci\u00f3n y amor.<\/p>\n<p>FUENTE: <a href=\"https:\/\/www.causes.com\/causes\/467572-cuidemos-a-ninos-y-ancianos\/updates\/330201-de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\" target=\"_blank\">causes.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos. Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan. Algunos ancianos tienen la dicha de que sus vidas sean m\u00e1s largas[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1550","post","type-post","status-publish","format-standard","hentry","category-ayuda-a-domicilio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo? - Mujer Rural Emprendedora<\/title>\n<meta name=\"description\" content=\"Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos. Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo? - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos. Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-12T10:47:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-12T10:48:34+00:00\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo?\",\"datePublished\":\"2015-06-12T10:47:37+00:00\",\"dateModified\":\"2015-06-12T10:48:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/\"},\"wordCount\":692,\"commentCount\":0,\"articleSection\":[\"Ayuda a Domicilio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/\",\"name\":\"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo? - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"datePublished\":\"2015-06-12T10:47:37+00:00\",\"dateModified\":\"2015-06-12T10:48:34+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"description\":\"Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos. Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo? - Mujer Rural Emprendedora","description":"Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos. Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo? - Mujer Rural Emprendedora","og_description":"Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos. Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan.","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-06-12T10:47:37+00:00","article_modified_time":"2015-06-12T10:48:34+00:00","author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo?","datePublished":"2015-06-12T10:47:37+00:00","dateModified":"2015-06-12T10:48:34+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/"},"wordCount":692,"commentCount":0,"articleSection":["Ayuda a Domicilio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/","name":"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo? - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"datePublished":"2015-06-12T10:47:37+00:00","dateModified":"2015-06-12T10:48:34+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"description":"Proporcion\u00e1ndoles los cuidados que ellos merecen, alimentos balanceados, mejor atenci\u00f3n m\u00e9dica, un mejor estilo de vida, atenci\u00f3n en todos los aspectos. Si logramos compenetrarnos en su interior y captar sus necesidades podremos otorgarles lo que ellos realmente necesitan.","breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/de-que-forma-podemos-ayudar-a-que-nuestros-ancianos-vivan-mas-tiempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfDe que forma podemos ayudar a que nuestros ancianos vivan m\u00e1s tiempo?"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=1550"}],"version-history":[{"count":2,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1550\/revisions"}],"predecessor-version":[{"id":1552,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1550\/revisions\/1552"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=1550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=1550"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=1550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}