{"id":1701,"date":"2015-07-06T10:00:22","date_gmt":"2015-07-06T10:00:22","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=1701"},"modified":"2015-07-06T10:00:22","modified_gmt":"2015-07-06T10:00:22","slug":"fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/","title":{"rendered":"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza"},"content":{"rendered":"<p class=\"entradilla\">La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.<\/p>\n<p>La jornada ha contado con m\u00e1s de 160 personas que han acudido para mejorar sus competencias profesionales en busca de una oportunidad laboral y para conocer nuevos nichos de empleo emergentes.<\/p>\n<p>La inauguraci\u00f3n ha corrido a cargo del diputado del \u00c1rea de Igualdad y Desarrollo Local de la Diputaci\u00f3n de Badajoz, Manuel D\u00edaz; el alcalde de la localidad, Manuel Gonz\u00e1lez; y el director gerente de la C\u00e1mara Oficial de Comercio e Industria de Badajoz, Antonio Masa.<\/p>\n<p>Todos ellos han coincidido en la \u00abefectividad\u00bb de la colaboraci\u00f3n p\u00fablico-privada, en la \u00aboportunidad\u00bb que supone alinear las diferentes estrategias pol\u00edticas y en la necesidad de trabajar en la formaci\u00f3n continua con las personas y empresas del territorio.<\/p>\n<p>Durante la feria, los asistentes han podido participar en diferentes espacios especialmente dise\u00f1ados para desempleados, emprendedores y empresas, seg\u00fan ha informado la Diputaci\u00f3n de Badajoz en nota de prensa.<\/p>\n<p>Cabe destacar que el programa ha comenzado con la charla entre el director del \u00c1rea de Desarrollo Local de la Diputaci\u00f3n de Badajoz, Javier Luna, y la directora del \u00c1rea de Estrategia y Desarrollo Empresarial de la C\u00e1mara Oficial de Comercio e Industria de Badajoz, Isabel Balbont\u00edn.<\/p>\n<p>Ambos han se\u00f1alado a los CID como punto de encuentro de entidades, organizaciones, empresas y ciudadan\u00eda en el territorio, ya que son espacios \u00abcercanos\u00bb que pretenden convertirse en nodos de innovaci\u00f3n, cooperaci\u00f3n y apoyo para el momento socio-econ\u00f3mico que estamos viviendo.<\/p>\n<p>Adem\u00e1s, Balbont\u00edn ha dado a conocer la plataforma gratuita www.aprendeafinanciarte.com, especialmente dise\u00f1ada para ayudar a emprendedores\/as y empresas a buscar la financiaci\u00f3n y\/o ayuda que mejor se adapte a su realidad. Por su parte, el consultor en valores Jaime Ruiz Pe\u00f1a ha sido el encargado de realizar la ponencia inaugural.<\/p>\n<h2 class=\"ladillo\">Talleres<\/h2>\n<p>Los talleres han buscado transmitir experiencias \u00abreales\u00bb y herramientas \u00ab\u00fatiles\u00bb capaces de dar un nuevo enfoque en la b\u00fasqueda de empleo, en la creaci\u00f3n de una nueva iniciativa o en la consolidaci\u00f3n empresarial.<\/p>\n<p>En este sentido, la CEO de Social&amp;Tech, Fernanda Jaramillo, en el taller de &#8216;Identidad Digital: competencias digitales y marca personal para el empleo&#8217;, ha transmitido que los profesionales de este siglo ven en la tecnolog\u00eda un \u00abaliado\u00bb que les permite visibilizar su talento y trabajar desde lo local con cualquier parte el mundo.<\/p>\n<p>A continuaci\u00f3n Alejando Almenara, CEO de Inexsos, en el taller de \u00abEconom\u00eda colaborativa: nuevos nichos de mercado para emprender\u00bb ha mostrado que la sociedad conectada y en Red est\u00e1 generando un nuevo modelo de consumo, basado en el pro-com\u00fan, m\u00e1s sostenible y creativo.<\/p>\n<p>Despu\u00e9s, David S\u00e1nchez, CEO de PayperThink, en el taller &#8216;Plan de acci\u00f3n para la b\u00fasqueda de empleo efectiva&#8217;, ha trabajado en las creencias y en la necesidad del establecimiento de objetivos concretos para trazar un plan que acerque al destino, a la vez que ha puesto el enfoque en el cliente como el elemento m\u00e1s importante para desarrollar un emprendimiento.<\/p>\n<p>De forma paralela a los talleres se desarrollaron otros espacios como &#8216;Caf\u00e9 &amp; Networking&#8217;, especialmente pensado para generar nuevas conversaciones y oportunidades de colaboraci\u00f3n en torno a un caf\u00e9; &#8216;Haciendo comarca&#8217;, iniciativa pensada para acercar a las instituciones y dar a conocer los diferentes programas y ayudas que pueden ser de utilidad; y la zona &#8216;Tu video&#8217;, en la que fue posible grabar v\u00eddeo curr\u00edculum para la b\u00fasqueda de empleo a trav\u00e9s de Internet.<\/p>\n<p>De la misma manera, destaca la zona &#8216;Aporto Valor&#8217;, en la que empresas han buscado nuevos perfiles profesionales para incorporarlos a su equipo. En total siete empresas (Almacenes Olivenza, Caser Olivenza, Cristian Lay, Palacio Arteaga. OPI Aupex, OPI Coeba, Sadimba), 21 ofertas de empleo y 120 entrevistas de trabajo realizadas, seg\u00fan ha informado la instituci\u00f3n provincial.<\/p>\n<p>En esta Feria de Empleo, Emprendimiento y Empresa tambi\u00e9n ha participado Fernando Berl\u00edn de Radio Cable a trav\u00e9s de videoconferencia, quien ha mostrado su experiencia como emprendedor y ha compartido los elementos que le han ayudado a conseguir el \u00e9xito.<\/p>\n<p>De forma pionera en dicha feria, se ha desarrollado un Networking Profesional en el que 14 empresas de la Comarca de Olivenza han podido dar a conocer su iniciativa, abrir nuevas conversaciones para generar ideas que complementen su cat\u00e1logo de servicios y ver que existen inquietudes comunes para la consolidaci\u00f3n empresarial.<\/p>\n<p>La Feria se enmarca en el Programa Local de Apoyo al Empleo (PLAE), cofinanciado en un 80 por ciento por el Fondo Social Europeo y en un 20 por ciento por fondos propios de la Diputaci\u00f3n de Badajoz y de la C\u00e1mara de Comercio de Badajoz.<\/p>\n<p>En esta ocasi\u00f3n ha contado con la colaboraci\u00f3n del Grupo de Acci\u00f3n Local Aderco, la Mancomunidad Integral de la Comarca de Olivenza, Ceiprex Extremadura, Acesco, Consejo de la Juventud de Extremadura y en el Sexpe<\/p>\n<p>FUENTE: <a href=\"http:\/\/La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.  La jornada ha contado con m\u00e1s de 160 personas que han acudido para mejorar sus competencias profesionales en busca de una oportunidad laboral y para conocer nuevos nichos de empleo emergentes.  La inauguraci\u00f3n ha corrido a cargo del diputado del \u00c1rea de Igualdad y Desarrollo Local de la Diputaci\u00f3n de Badajoz, Manuel D\u00edaz; el alcalde de la localidad, Manuel Gonz\u00e1lez; y el director gerente de la C\u00e1mara Oficial de Comercio e Industria de Badajoz, Antonio Masa.  Todos ellos han coincidido en la &quot;efectividad&quot; de la colaboraci\u00f3n p\u00fablico-privada, en la &quot;oportunidad&quot; que supone alinear las diferentes estrategias pol\u00edticas y en la necesidad de trabajar en la formaci\u00f3n continua con las personas y empresas del territorio.  Durante la feria, los asistentes han podido participar en diferentes espacios especialmente dise\u00f1ados para desempleados, emprendedores y empresas, seg\u00fan ha informado la Diputaci\u00f3n de Badajoz en nota de prensa.  Cabe destacar que el programa ha comenzado con la charla entre el director del \u00c1rea de Desarrollo Local de la Diputaci\u00f3n de Badajoz, Javier Luna, y la directora del \u00c1rea de Estrategia y Desarrollo Empresarial de la C\u00e1mara Oficial de Comercio e Industria de Badajoz, Isabel Balbont\u00edn.  Ambos han se\u00f1alado a los CID como punto de encuentro de entidades, organizaciones, empresas y ciudadan\u00eda en el territorio, ya que son espacios &quot;cercanos&quot; que pretenden convertirse en nodos de innovaci\u00f3n, cooperaci\u00f3n y apoyo para el momento socio-econ\u00f3mico que estamos viviendo.  Adem\u00e1s, Balbont\u00edn ha dado a conocer la plataforma gratuita www.aprendeafinanciarte.com, especialmente dise\u00f1ada para ayudar a emprendedores\/as y empresas a buscar la financiaci\u00f3n y\/o ayuda que mejor se adapte a su realidad. Por su parte, el consultor en valores Jaime Ruiz Pe\u00f1a ha sido el encargado de realizar la ponencia inaugural.  Talleres Los talleres han buscado transmitir experiencias &quot;reales&quot; y herramientas &quot;\u00fatiles&quot; capaces de dar un nuevo enfoque en la b\u00fasqueda de empleo, en la creaci\u00f3n de una nueva iniciativa o en la consolidaci\u00f3n empresarial.  En este sentido, la CEO de Social&amp;Tech, Fernanda Jaramillo, en el taller de 'Identidad Digital: competencias digitales y marca personal para el empleo', ha transmitido que los profesionales de este siglo ven en la tecnolog\u00eda un &quot;aliado&quot; que les permite visibilizar su talento y trabajar desde lo local con cualquier parte el mundo.  A continuaci\u00f3n Alejando Almenara, CEO de Inexsos, en el taller de &quot;Econom\u00eda colaborativa: nuevos nichos de mercado para emprender&quot; ha mostrado que la sociedad conectada y en Red est\u00e1 generando un nuevo modelo de consumo, basado en el pro-com\u00fan, m\u00e1s sostenible y creativo.  Despu\u00e9s, David S\u00e1nchez, CEO de PayperThink, en el taller 'Plan de acci\u00f3n para la b\u00fasqueda de empleo efectiva', ha trabajado en las creencias y en la necesidad del establecimiento de objetivos concretos para trazar un plan que acerque al destino, a la vez que ha puesto el enfoque en el cliente como el elemento m\u00e1s importante para desarrollar un emprendimiento.  De forma paralela a los talleres se desarrollaron otros espacios como 'Caf\u00e9 &amp; Networking', especialmente pensado para generar nuevas conversaciones y oportunidades de colaboraci\u00f3n en torno a un caf\u00e9; 'Haciendo comarca', iniciativa pensada para acercar a las instituciones y dar a conocer los diferentes programas y ayudas que pueden ser de utilidad; y la zona 'Tu video', en la que fue posible grabar v\u00eddeo curr\u00edculum para la b\u00fasqueda de empleo a trav\u00e9s de Internet.  De la misma manera, destaca la zona 'Aporto Valor', en la que empresas han buscado nuevos perfiles profesionales para incorporarlos a su equipo. En total siete empresas (Almacenes Olivenza, Caser Olivenza, Cristian Lay, Palacio Arteaga. OPI Aupex, OPI Coeba, Sadimba), 21 ofertas de empleo y 120 entrevistas de trabajo realizadas, seg\u00fan ha informado la instituci\u00f3n provincial.  En esta Feria de Empleo, Emprendimiento y Empresa tambi\u00e9n ha participado Fernando Berl\u00edn de Radio Cable a trav\u00e9s de videoconferencia, quien ha mostrado su experiencia como emprendedor y ha compartido los elementos que le han ayudado a conseguir el \u00e9xito.  De forma pionera en dicha feria, se ha desarrollado un Networking Profesional en el que 14 empresas de la Comarca de Olivenza han podido dar a conocer su iniciativa, abrir nuevas conversaciones para generar ideas que complementen su cat\u00e1logo de servicios y ver que existen inquietudes comunes para la consolidaci\u00f3n empresarial.  La Feria se enmarca en el Programa Local de Apoyo al Empleo (PLAE), cofinanciado en un 80 por ciento por el Fondo Social Europeo y en un 20 por ciento por fondos propios de la Diputaci\u00f3n de Badajoz y de la C\u00e1mara de Comercio de Badajoz.  En esta ocasi\u00f3n ha contado con la colaboraci\u00f3n del Grupo de Acci\u00f3n Local Aderco, la Mancomunidad Integral de la Comarca de Olivenza, Ceiprex Extremadura, Acesco, Consejo de la Juventud de Extremadura y en el Sexpe\" target=\"_blank\">expansi\u00f3n.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas. La jornada ha contado con m\u00e1s de 160 personas que han acudido para mejorar sus competencias profesionales en busca de una oportunidad laboral y para[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1701","post","type-post","status-publish","format-standard","hentry","category-emprendedores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza - Mujer Rural Emprendedora<\/title>\n<meta name=\"description\" content=\"La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-06T10:00:22+00:00\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza\",\"datePublished\":\"2015-07-06T10:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/\"},\"wordCount\":868,\"commentCount\":0,\"articleSection\":[\"Emprendedores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/\",\"name\":\"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"datePublished\":\"2015-07-06T10:00:22+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"description\":\"La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza - Mujer Rural Emprendedora","description":"La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/","og_locale":"es_ES","og_type":"article","og_title":"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza - Mujer Rural Emprendedora","og_description":"La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-07-06T10:00:22+00:00","author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza","datePublished":"2015-07-06T10:00:22+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/"},"wordCount":868,"commentCount":0,"articleSection":["Emprendedores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/","name":"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"datePublished":"2015-07-06T10:00:22+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"description":"La Feria de Empleo, Emprendimiento y Empresa ha congregado en Olivenza (Badajoz) a siete empresas con 21 ofertas de empleo y 120 entrevistas laborales realizadas.","breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/fin-de-semana-para-feria-de-empleo-emprendimiento-y-empresa-de-olivenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"Fin de semana para Feria de Empleo, Emprendimiento y Empresa de Olivenza"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=1701"}],"version-history":[{"count":1,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1701\/revisions"}],"predecessor-version":[{"id":1702,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/1701\/revisions\/1702"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=1701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=1701"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=1701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}