{"id":652,"date":"2015-02-25T10:42:42","date_gmt":"2015-02-25T10:42:42","guid":{"rendered":"http:\/\/www.mujerruralemprendedora.com\/es\/?p=652"},"modified":"2015-03-01T20:01:58","modified_gmt":"2015-03-01T20:01:58","slug":"presentacion-mujer-rural-emprendedora-murcia","status":"publish","type":"post","link":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/","title":{"rendered":"Presentaci\u00f3n del programa \u00bb Mujer Rural Emprendedora\u00bb en Murcia"},"content":{"rendered":"<p>La presidenta de la Asociacion de Familias y Mujeres del Medio Rural (AFAMMER) de la regi\u00f3n de Murcia, Carmen Ingl\u00e9s, presentaba \u00a0junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d, que se est\u00e1 desarrollando en las comunidades aut\u00f3nomas de Regi\u00f3n de Murcia, Castilla-La Mancha y La Rioja.<br \/>\nSe trata de un importante e innovador proyecto que, seg\u00fan ha destacado Carmen Ingl\u00e9s, \u201cest\u00e1 dirigido a la potenciaci\u00f3n de la creaci\u00f3n de empleo a trav\u00e9s del emprendimiento femenino en el medio rural en el sector de la dependencia y la ayuda a domicilio ya que desde AFAMMER seguimos entendiendo que el empleo es el primer pilar para alcanzar la igualdad\u201d.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/b6kSkVRGHNk\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>El proyecto esta subvencionado por el Instituto de la Mujer dentro de la convocatoria Eea Grants derivada del acuerdo de Entendimiento entre Espa\u00f1a, Noruega, Islandia y Liechtenstein, y cofinanciado por Bankia.<br \/>\nCarmen Ingl\u00e9s ha destacado que AFAMMER present\u00f3 este proyecto en base al estudio preliminar realizado en las tres comunidades aut\u00f3nomas en las que se est\u00e1 desarrollando, seg\u00fan el cual se constat\u00f3 que la tasa de desempleo sigue siendo superior en las mujeres que en los hombres y el incremento en la tasa de dependencia debido al envejecimiento de la poblaci\u00f3n y al aumento de la esperanza de vida, tasa que, seg\u00fan ha afirmado \u201cen Castilla-La Mancha se sit\u00faa en el 26,9%; en Murcia en el 20,5% y en La Rioja en el 29,3%, por lo que la creaci\u00f3n de empresas dedicadas a la atenci\u00f3n a las personas mayores y\/o dependientes es una oportunidad de empleo en el medio rural para las mujeres emprendedoras\u201d.<br \/>\nAs\u00ed mismo present\u00f3 la plataforma virtual que nace con un claro objetivo: formar y ofrecer todas las herramientas necesarias para que la mujer rural pueda emprender en el sector de la dependencia y la ayuda a domicilio.<br \/>\nEsta plataforma (www.mujerruralemprendedora.com) desarrollada por AFAMMER, se pone en marcha en las comunidades aut\u00f3nomas de Castilla la Mancha, Murcia y la Rioja.<br \/>\nSe podr\u00e1 encontrar todo lo necesario para la formaci\u00f3n en ayuda a domicilio y dependencia, informaci\u00f3n \u00fatil en el sector, ayudas para el emprendimiento, ofertas de empleo, en definitiva se trata de un innovador proyecto que est\u00e1 dirigido a la potenciaci\u00f3n de la creaci\u00f3n de empleo a trav\u00e9s del emprendimiento femenino en el medio rural.<br \/>\nAdem\u00e1s buscamos la participaci\u00f3n de todas aquellas mujeres emprendedoras que quieran exponer sus experiencias, difundir sus empresas para aumentar sus posibilidades de empleo as\u00ed como recibir informaci\u00f3n relacionada con la actividad empresarial y con el sector de la dependencia y la ayuda a domicilio.<br \/>\nUn proyecto que sale a la luz despu\u00e9s de un estudio preliminar realizado en las tres comunidades aut\u00f3nomas en las que se est\u00e1 desarrollando, seg\u00fan el cual se constat\u00f3 que la tasa de desempleo sigue siendo superior en las mujeres que en los hombres y el incremento en la tasa de dependencia debido al envejecimiento de la poblaci\u00f3n.<br \/>\nNacemos con vocaci\u00f3n de ayudar, de potenciar el empleo femenino, de apoyar a la mujer rural. Porque ella es el futuro de cada uno de nuestros pueblos. Su trabajo es nuestra esperanza y cada una de sus experiencias hay que compartirla.<br \/>\nEn los pr\u00f3ximos meses y dentro de este proyecto, est\u00e1 previsto que se desarrollen cursos de competencias c\u00edvicas y sociales, emprendimiento y de Cuidados y necesidades de las personas mayores dependientes en el municipio de Torre Pacheco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de la Asociacion de Familias y Mujeres del Medio Rural (AFAMMER) de la regi\u00f3n de Murcia, Carmen Ingl\u00e9s, presentaba \u00a0junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d, que se est\u00e1 desarrollando en[&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6],"tags":[],"class_list":["post-652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayuda-a-domicilio","category-emprendedores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentaci\u00f3n del programa &quot; Mujer Rural Emprendedora&quot; en Murcia - Mujer Rural Emprendedora<\/title>\n<meta name=\"description\" content=\"La presidenta de Murcia presentaba junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci\u00f3n del programa &quot; Mujer Rural Emprendedora&quot; en Murcia - Mujer Rural Emprendedora\" \/>\n<meta property=\"og:description\" content=\"La presidenta de Murcia presentaba junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujer Rural Emprendedora\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mujerruralemprendedora\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-25T10:42:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-03-01T20:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.mujerruralemprendedora.com\/es\/wp-content\/uploads\/sites\/3\/2015\/02\/proyecto-murcia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"809\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mjesus\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mjesus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/\"},\"author\":{\"name\":\"mjesus\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"headline\":\"Presentaci\u00f3n del programa \u00bb Mujer Rural Emprendedora\u00bb en Murcia\",\"datePublished\":\"2015-02-25T10:42:42+00:00\",\"dateModified\":\"2015-03-01T20:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/\"},\"wordCount\":619,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2015\\\/02\\\/proyecto-murcia.jpg\",\"articleSection\":[\"Ayuda a Domicilio\",\"Emprendedores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/\",\"name\":\"Presentaci\u00f3n del programa \\\" Mujer Rural Emprendedora\\\" en Murcia - Mujer Rural Emprendedora\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2015\\\/02\\\/proyecto-murcia.jpg\",\"datePublished\":\"2015-02-25T10:42:42+00:00\",\"dateModified\":\"2015-03-01T20:01:58+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\"},\"description\":\"La presidenta de Murcia presentaba junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2015\\\/02\\\/proyecto-murcia.jpg\",\"contentUrl\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2015\\\/02\\\/proyecto-murcia.jpg\",\"width\":1440,\"height\":809,\"caption\":\"mujer rural emprendedora ayuda domicilio afammer mayores videos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/presentacion-mujer-rural-emprendedora-murcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaci\u00f3n del programa \u00bb Mujer Rural Emprendedora\u00bb en Murcia\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#website\",\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/\",\"name\":\"Mujer Rural Emprendedora\",\"description\":\"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/#\\\/schema\\\/person\\\/bef3305571cafa6b1960c301df7452ea\",\"name\":\"mjesus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g\",\"caption\":\"mjesus\"},\"url\":\"http:\\\/\\\/www.mujerruralemprendedora.com\\\/es\\\/author\\\/mjesus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaci\u00f3n del programa \" Mujer Rural Emprendedora\" en Murcia - Mujer Rural Emprendedora","description":"La presidenta de Murcia presentaba junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaci\u00f3n del programa \" Mujer Rural Emprendedora\" en Murcia - Mujer Rural Emprendedora","og_description":"La presidenta de Murcia presentaba junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d","og_url":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/","og_site_name":"Mujer Rural Emprendedora","article_publisher":"http:\/\/www.facebook.com\/mujerruralemprendedora","article_published_time":"2015-02-25T10:42:42+00:00","article_modified_time":"2015-03-01T20:01:58+00:00","og_image":[{"width":1440,"height":809,"url":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-content\/uploads\/sites\/3\/2015\/02\/proyecto-murcia.jpg","type":"image\/jpeg"}],"author":"mjesus","twitter_misc":{"Escrito por":"mjesus","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#article","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/"},"author":{"name":"mjesus","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"headline":"Presentaci\u00f3n del programa \u00bb Mujer Rural Emprendedora\u00bb en Murcia","datePublished":"2015-02-25T10:42:42+00:00","dateModified":"2015-03-01T20:01:58+00:00","mainEntityOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/"},"wordCount":619,"commentCount":0,"image":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-content\/uploads\/sites\/3\/2015\/02\/proyecto-murcia.jpg","articleSection":["Ayuda a Domicilio","Emprendedores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/","url":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/","name":"Presentaci\u00f3n del programa \" Mujer Rural Emprendedora\" en Murcia - Mujer Rural Emprendedora","isPartOf":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#primaryimage"},"image":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#primaryimage"},"thumbnailUrl":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-content\/uploads\/sites\/3\/2015\/02\/proyecto-murcia.jpg","datePublished":"2015-02-25T10:42:42+00:00","dateModified":"2015-03-01T20:01:58+00:00","author":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea"},"description":"La presidenta de Murcia presentaba junto a la alcaldesa de Torre Pacheco, Fina Mar\u00edn, el proyecto \u201cLas Mujeres y las Nuevas Tecnolog\u00edas en la Dinamizaci\u00f3n Econ\u00f3mica del Medio Rural\u201d","breadcrumb":{"@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#primaryimage","url":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-content\/uploads\/sites\/3\/2015\/02\/proyecto-murcia.jpg","contentUrl":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-content\/uploads\/sites\/3\/2015\/02\/proyecto-murcia.jpg","width":1440,"height":809,"caption":"mujer rural emprendedora ayuda domicilio afammer mayores videos"},{"@type":"BreadcrumbList","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/presentacion-mujer-rural-emprendedora-murcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/www.mujerruralemprendedora.com\/es\/"},{"@type":"ListItem","position":2,"name":"Presentaci\u00f3n del programa \u00bb Mujer Rural Emprendedora\u00bb en Murcia"}]},{"@type":"WebSite","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#website","url":"http:\/\/www.mujerruralemprendedora.com\/es\/","name":"Mujer Rural Emprendedora","description":"Otro sitio m\u00e1s de Sitios de Mujer Rural Emprendedora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.mujerruralemprendedora.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"http:\/\/www.mujerruralemprendedora.com\/es\/#\/schema\/person\/bef3305571cafa6b1960c301df7452ea","name":"mjesus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c2c08cfb2f5ecbf35952659564347799503b54d1d61bcb2b159c7dde6af69f4?s=96&d=mm&r=g","caption":"mjesus"},"url":"http:\/\/www.mujerruralemprendedora.com\/es\/author\/mjesus\/"}]}},"_links":{"self":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/comments?post=652"}],"version-history":[{"count":6,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/652\/revisions"}],"predecessor-version":[{"id":726,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/posts\/652\/revisions\/726"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media\/653"}],"wp:attachment":[{"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/media?parent=652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/categories?post=652"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mujerruralemprendedora.com\/es\/wp-json\/wp\/v2\/tags?post=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}